{"id":681,"date":"2020-11-06T08:20:09","date_gmt":"2020-11-06T11:20:09","guid":{"rendered":"https:\/\/paulaibanez.cl\/blog\/?p=681"},"modified":"2021-03-20T09:15:01","modified_gmt":"2021-03-20T12:15:01","slug":"como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar","status":"publish","type":"post","link":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/","title":{"rendered":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\"><em>Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.&nbsp;<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No es lo mismo empezar bien el d\u00eda, con tiempo, tomando un buen desayuno, que corriendo de ac\u00e1 para all\u00e1, medio comiendo algo mientras te vistes. O si antes de iniciar la jornada laboral, tuviste que perder tiempo valioso en el tr\u00e1fico o en&nbsp;<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/como-prestar-atencion-a-tu-atencion\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/como-prestar-atencion-a-tu-atencion\/\" target=\"_blank\" rel=\"noreferrer noopener\">teletrabajo<\/a><\/strong>, que tengas que abrir el d\u00eda peleando con la compa\u00f1\u00eda distribuidora de internet porque no te funciona \u00bfTe ha sucedido?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cHay d\u00edas que siento que voy a romper un r\u00e9cord mundial y otros con ganas de irme a&nbsp;&nbsp;dormir para que el d\u00eda se acabe\u201d <\/p><cite>M\u00f3nICA, GERENTE DE IT<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esa frase fue lo primero que escuch\u00e9 de M\u00f3nica cuando la conoc\u00ed, lleg\u00f3 a tomar coaching conmigo, advert\u00eda que cada d\u00eda rend\u00eda menos \u00bfQu\u00e9 hac\u00eda a M\u00f3nica sentir as\u00ed? \u00bfEra posible equilibrar m\u00e1s su energ\u00eda?, estuvimos trabajando juntas por varios meses y en estas lineas te contar\u00e9 como logr\u00f3 identificar como la negatividad que la rodeaba era la fuente de sus cambios de humor, des\u00e1nimo y disminuci\u00f3n de desempe\u00f1o laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudios de Rothbard y Wilk (2011) mostraron como el estado de \u00e1nimo en el trabajo se relaciona con el rendimiento, los colaboradores que iniciaban el d\u00eda tranquilos o felices pod\u00edan continuar as\u00ed todo el d\u00eda y \u201cla interacci\u00f3n con clientes tend\u00eda a mejorar su estado de \u00e1nimo\u201d. Pero las personas que que iniciaron con un d\u00eda \u201cgris\u201d, como descrito en el parrafo anterior, se mantuvieron as\u00ed y al final del d\u00eda se sentieron peor, aunque hayan interactuado con personas positivas durante el d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s sorprende del estudio fue que personas que iniciaban el d\u00eda con \u201cun mal d\u00eda\u201d, al interactuar con clientes de mal humor, tend\u00edan a mejorarlo un poco, quiz\u00e1s porque mirando desde la perspectiva del cliente, quiz\u00e1s sus vidas no eran tan terribles, como lo hab\u00edan sentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo estudio revel\u00f3 que los colaboradores con \u00e1nimo negativo, tendieron a tomar descansos m\u00e1s frecuentes en sus tareas, pudiendo llegar al final del estudio a un 10% de perdida de productividad. Necesitaban ese tiempo para descansar y poder hacer frente al&nbsp;<a href=\"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/\" target=\"_blank\" rel=\"noreferrer noopener\">estr\u00e9s<\/a>&nbsp;que sent\u00edan.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Presionar el boton de Re-start<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"595\" data-attachment-id=\"1008\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/captura-de-pantalla-2021-02-06-a-las-19-48-38\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?fit=762%2C595&amp;ssl=1\" data-orig-size=\"762,595\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2021-02-06-a-las-19.48.38\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?fit=762%2C595&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?fit=600%2C469&amp;ssl=1\" data-orig-src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?fit=600%2C469&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-1008\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27762%27%20height%3D%27595%27%20viewBox%3D%270%200%20762%20595%27%3E%3Crect%20width%3D%27762%27%20height%3D%273595%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?resize=200%2C156&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?resize=300%2C234&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?resize=400%2C312&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?resize=600%2C469&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-06-a-las-19.48.38.png?fit=762%2C595&amp;ssl=1 762w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCada vez que mi computadora no funciona, la reinicio, pero a mi no me sucede lo&nbsp;&nbsp;mismo Paula\u201d, me dijo Carlos en una sesi\u00f3n de coaching, se sent\u00eda desgastado.&nbsp;&nbsp;Ese d\u00eda luego de muchas preguntas se di\u00f3 cuenta como le afectaba iniciar la ma\u00f1ana discutiendo con su hijo adolescente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego hablamos del impacto de los d\u00edas dif\u00edciles en sus colaboradores en su jornada laboral \u00bfPodr\u00eda de alguna manera ayudarlos? \u00bfC\u00f3mo podr\u00eda ser un mejor <a rel=\"noreferrer noopener\" href=\"https:\/\/paulaibanez.cl\/blog\/ser-lider-de-un-equipo-no-es-un-trabajo-facil-test-mindset\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/ser-lider-de-un-equipo-no-es-un-trabajo-facil-test-mindset\/\" target=\"_blank\"><strong>l\u00edder<\/strong><\/a>? Decidi\u00f3 impactar positivamente en ellos, ten\u00eda una <a href=\"https:\/\/paulaibanez.cl\/blog\/tipos-de-mentalidades-para-un-liderazgo-exitoso\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/tipos-de-mentalidades-para-un-liderazgo-exitoso\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>mentalidad de aprendiza<\/strong><\/a><strong><a href=\"https:\/\/paulaibanez.cl\/blog\/tipos-de-mentalidades-para-un-liderazgo-exitoso\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/tipos-de-mentalidades-para-un-liderazgo-exitoso\/\" target=\"_blank\" rel=\"noreferrer noopener\">j<\/a>e<\/strong> y dise\u00f1amos un plan de acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f3nica y Carlos de forma separada, producto de su propia reflexi\u00f3n mediante&nbsp;<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/el-poder-de-las-preguntas-apropiadas-en-el-ambiente-correcto\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/el-poder-de-las-preguntas-apropiadas-en-el-ambiente-correcto\/\" target=\"_blank\" rel=\"noreferrer noopener\">preguntas poderosas<\/a>,&nbsp;<\/strong>llegaron a conclusiones parecidas, el d\u00eda se ve\u00eda profundamene influenciado seg\u00fan la forma que iniciaba. Una mala ma\u00f1ana, era sin\u00f3nimo de un d\u00eda agotador y negativo. Y ni hablar si hab\u00edan dormido mal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos se comprometieron a casi las mismas tareas, cada ma\u00f1ana enviar\u00edan un mail a sus colaboradores, con mensaje positivo para impulsar el d\u00eda, no s\u00f3lo recalcando lo que no hab\u00edan hecho bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se comprometieron a respetar un plan de alimentaci\u00f3n durante el d\u00eda, para tomar <a href=\"https:\/\/paulaibanez.cl\/blog\/9-formas-de-mejorar-por-completo-la-toma-de-decision\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/9-formas-de-mejorar-por-completo-la-toma-de-decision\/\" target=\"_blank\" rel=\"noreferrer noopener\">mejores decisiones<\/a>. Este punto, es fundamental, al igual que beber agua, ya que se utiliza mucha energ\u00eda al usar las \u00e1reas m\u00e1s evolucionas del cerebro como es el cortex prefrontal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cortex prefrontal est\u00e1 encargado de las capacidades elevadas como las funciones ejecutivas&nbsp;&nbsp;de planificar, ejecutar, organizar de procesos, de la flexibilidad entre otras y tambi\u00e9n de las funciones cognitivas como atenci\u00f3n selectiva, razonamiento, memoria y lenguaje.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1600\" data-attachment-id=\"1106\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/diseno-sin-titulo-18\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?fit=2000%2C1600&amp;ssl=1\" data-orig-size=\"2000,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Diseno-sin-titulo-18\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?fit=1024%2C819&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?fit=600%2C480&amp;ssl=1\" data-orig-src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?fit=600%2C480&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-1106\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272000%27%20height%3D%271600%27%20viewBox%3D%270%200%202000%201600%27%3E%3Crect%20width%3D%272000%27%20height%3D%2731600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=200%2C160&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=400%2C320&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=600%2C480&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=768%2C614&amp;ssl=1 768w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=800%2C640&amp;ssl=1 800w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=1024%2C819&amp;ssl=1 1024w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=1200%2C960&amp;ssl=1 1200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?resize=1536%2C1229&amp;ssl=1 1536w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-18.jpg?fit=2000%2C1600&amp;ssl=1 2000w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estimularon a su equipo a respetar los horarios de comida y nunca iniciar la jornada laboral sin tomar desayuno. \u00bfRespetas los tuyos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de sus acuerdos fue celebrar los logros en conjunto a su equipo, por medio de alguna actividad simb\u00f3lica, como al inicio de las reuniones mencionarlo y estimular al resto a lograrlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos reflexion\u00f3, como una pr\u00e1ctica que parec\u00eda inofensiva y casi le daba orgullo de si, ten\u00eda una repercusi\u00f3n negativa en su equipo. En las noches como le costaba quedarse dormido, decid\u00eda mandar todos los mails que no hab\u00eda mandado en el d\u00eda, haciendo las ma\u00f1anas del resto desagradable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No mandar\u00eda cientos de mails en la noche, sino los program\u00f3 para que llegaran unos 20 minutos despu\u00e9s del inicio de la jornada laboral, para no hacer m\u00e1s dificil el inicio de todos. Entendi\u00f3 que no se trataba solamente de enviarlos, sino de que las personas los tomaran de buena forma, con el estado animo adecuado,&nbsp;&nbsp;para iniciar la ejecuci\u00f3n en las distintas tareas que ellos implicaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo se di\u00f3 cuenta lo necesario de tomar un descanso al llegar a la oficina. Te estar\u00e1s preguntado, pero \u00bfC\u00f3mo si est\u00e1 inciando el d\u00eda?, las rutinas familiares al desayuno, m\u00e1s el tr\u00e1fico, contestar llamadas mientras conduc\u00eda, lo hac\u00eda llegar de mal humor, \u201ciniciar el d\u00eda con el pie izquierdo\u201d&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1600\" data-attachment-id=\"1107\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/diseno-sin-titulo-20\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?fit=2000%2C1600&amp;ssl=1\" data-orig-size=\"2000,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Diseno-sin-titulo-20\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?fit=1024%2C819&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?fit=600%2C480&amp;ssl=1\" data-orig-src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?fit=600%2C480&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-1107\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272000%27%20height%3D%271600%27%20viewBox%3D%270%200%202000%201600%27%3E%3Crect%20width%3D%272000%27%20height%3D%2731600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=200%2C160&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=400%2C320&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=600%2C480&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=768%2C614&amp;ssl=1 768w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=800%2C640&amp;ssl=1 800w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=1024%2C819&amp;ssl=1 1024w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=1200%2C960&amp;ssl=1 1200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?resize=1536%2C1229&amp;ssl=1 1536w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Diseno-sin-titulo-20.jpg?fit=2000%2C1600&amp;ssl=1 2000w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, cuando se detuvo a observarse lo not\u00f3 r\u00e1pidamente. Lo conversamos en una sesi\u00f3n y se permiti\u00f3 tomar 10 minutos de descanso al llegar a la oficina, donde desconectaba su celular, escuchaba una lista de Spotify de viol\u00edn. Cargaba r\u00e1pidamente baterias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de probarlo un par de semanas, lo convers\u00f3 con su equipo y todos acordaron llegar 15 minutos antes, para poder descansar y as\u00ed iniciar con el estado de \u00e1nimo adecuado para enfrentar la jornada laboral. Disminuyeron los conflictos, mejor\u00f3 el clima de la oficina y sobre todo&nbsp;&nbsp;se sintieron m\u00e1s productivos,<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/paulaibanez.cl\/blog\/supera-la-procastinacion-acciona-tus-tareas-relevantes\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/supera-la-procastinacion-acciona-tus-tareas-relevantes\/\" target=\"_blank\">&nbsp;procrastinaron<\/a><\/strong> menos, el estr\u00e9s es tambi\u00e9n una fuente de posponer las tareas importantes para hacer las no importantes pero que te dan placer, como mira tu celular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f3nica instaur\u00f3 la rutina de sonre\u00edr un minuto antes de cruzar la puerta de entrada de la empresa, aunque no tuviera ganas de hacerlo. Es una excelente pr\u00e1ctica ya que el cerebro no reconoce si realmente est\u00e1s feliz o no, al realizar la mueca de la risa en tu cara, se liberan distintos neurotransmisores, sustancias que viajan entre neurona a neurona promoviendo un estado de bienestar. Incluso hacerlo varias veces al d\u00eda da resultados incre\u00edbles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los dos reconocieron como la negatividad estaba en sus vidas por todos lados, las noticias, las redes sociales, conversaciones que ten\u00edan con amigos \u201cest\u00e1 mala la cosa\u201d. A veces no hab\u00eda ni iniciado el d\u00eda y el pesismo reinante les generaba ansiedad.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Efectos t\u00f3xicos de la negatividad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa negatividad tiene efectos t\u00f3xicos\u201d, escribe Christina Porath docente de management de la universidad de George town en su libro \u201cMastering Civility: a manifesto for the workplace\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Relata como sus estudios han demostrado que frente a la negatividad, la rudeza, o la groseria, las personas se ven afectadas en su memoria de trabajo y en una disminuci\u00f3n del rendimiento, ya que se afecta la capacidad para procesar y recuperar la informaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso se ve afectada la comunicaci\u00f3n, ya que se cierran, se pierde el deseo de ser \u00fatil a los dem\u00e1s y todo esto puede disparar pensamientos disfuncionales y agresivos.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Crea tu plan de acci\u00f3n<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"438\" data-attachment-id=\"1101\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/tener-la-vida-que-quieres\/captura-de-pantalla-2021-03-13-a-las-10-16-18\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?fit=662%2C438&amp;ssl=1\" data-orig-size=\"662,438\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2021-03-13-a-las-10.16.18\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?fit=662%2C438&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?fit=600%2C397&amp;ssl=1\" data-orig-src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?fit=600%2C397&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-1101\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27662%27%20height%3D%27438%27%20viewBox%3D%270%200%20662%20438%27%3E%3Crect%20width%3D%27662%27%20height%3D%273438%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?resize=200%2C132&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?resize=400%2C265&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?resize=600%2C397&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/03\/Captura-de-Pantalla-2021-03-13-a-las-10.16.18.png?fit=662%2C438&amp;ssl=1 662w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En su libro adem\u00e1s recomienda las siguiente pr\u00e1cticas para que las personas experimenten sensaci\u00f3n de vitalidad en vez de sentirse agotadas y falta de&nbsp;<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/11-cosas-que-un-lider-debe-saber-sobre-la-confianza\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/11-cosas-que-un-lider-debe-saber-sobre-la-confianza\/\" target=\"_blank\" rel=\"noreferrer noopener\">confianza<\/a><\/strong>&nbsp;en si mismos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Evita la negatividad de las noticias y redes sociales, mantente informado, pero que no sea lo que te alimenta todo el d\u00eda<\/li><li>No caigas en el lenguaje negativo, ya que es muy poderoso. No es lo mismo decir \u201codio el inverno\u201d, que \u201cprefiero el verano\u201d<\/li><li>Concentrate en lo que puedes controlar, lo que no, que no se vuelva en alimento para una&nbsp;<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/la-mente-hipercritica\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/la-mente-hipercritica\/\" target=\"_blank\" rel=\"noreferrer noopener\">mente hipercr\u00edtica<\/a>,&nbsp;<\/strong>se proactiv@, ocupate de lo que si puedes hacer y en tus siguientes pasos, no en buscar culpables o caer en sobre an\u00e1lisis.<\/li><li>Administra bien tu energ\u00eda puede aumentar tu resistencia frente a la negatividad. Identifica los ladrones de energ\u00eda que no te dejan avanzar, aquellas tareas que no tienen que ver con tus metas y te dejan agotad@.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Idealmente saca los ladrones de energ\u00eda de tu vida, sino puedes, deja esas tareas para las franjas horarias que tienes menos energ\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los horarios que est\u00e1s con mayor energ\u00eda realiza las tareas que son importantes para cumplir tus metas y m\u00e1s a\u00fan si son las m\u00e1s dif\u00edciles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerda todas las personas tienen diferentes niveles de energ\u00eda y franjas horarias de ellas durante el d\u00eda, no te compares, sino aprovecha la tuya al m\u00e1ximo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"582\" data-attachment-id=\"939\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-liderar-la-diversidad-cognitiva-de-un-equipo\/captura-de-pantalla-2021-01-07-a-las-23-07-56\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?fit=760%2C582&amp;ssl=1\" data-orig-size=\"760,582\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2021-01-07-a-las-23.07.56\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?fit=760%2C582&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?fit=600%2C459&amp;ssl=1\" data-orig-src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?fit=600%2C459&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-939\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27760%27%20height%3D%27582%27%20viewBox%3D%270%200%20760%20582%27%3E%3Crect%20width%3D%27760%27%20height%3D%273582%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?resize=200%2C153&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?resize=300%2C230&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?resize=400%2C306&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?resize=600%2C459&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/01\/Captura-de-Pantalla-2021-01-07-a-las-23.07.56.png?fit=760%2C582&amp;ssl=1 760w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si crees que \u00e9ste art\u00edculo puede ayudar a m\u00e1s personas a entenderse, a mejorar su estado de animo, su<a href=\"https:\/\/paulaibanez.cl\/blog\/conoce-inteligencias-multiples-para-liderar-test\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/conoce-inteligencias-multiples-para-liderar-test\/\" target=\"_blank\" rel=\"noreferrer noopener\"> liderazgo<\/a> y motivaci\u00f3n, a comprender algunas situaciones en su equipo o las personas que est\u00e1n a su alrededor, te invito a compartirlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Genial si me puedes dejar un comentario, este post ha sido fruto de la inspiraci\u00f3n de algunos que recib\u00ed. As\u00ed este espacio que vuelve unos minutos de lectura de valor para ti<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerda suscribirte al blog.&nbsp;Semanalmente comparto informaci\u00f3n con conocimientos basados en neurociencias y coaching, aplicados al liderazgo, toma de decisiones, pensamiento, productividad, creatividad, entre otros. As\u00ed no te perder\u00e1s ning\u00fan art\u00edculo y conocer\u00e1s tips para seguir avanzando profesionalmente en un mundo cambiante y desafiante como el que hoy vivimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s leyendo en la computadora el final del blog puedes encontrar donde suscribirte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s desde tu m\u00f3vil, ve el final del blog y apreta \u201cver sitio completo\u201d, ah\u00ed te lleva a la p\u00e1gina, vas para abajo y te suscribes. (lo siento, wordpress no mejora esto a\u00fan para celulares, espero que pronto lo haga. \u00a1Pero te espero!!)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas gracias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.&nbsp; No es lo mismo empezar bien el d\u00eda, con tiempo, tomando un buen desayuno, que corriendo de ac\u00e1 para all\u00e1, medio comiendo algo mientras te vistes. O si antes de iniciar la jornada laboral, tuviste que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[259,262,261,102],"tags":[46,6,92,402,301,300,299],"class_list":["post-681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coaching","category-equipos-alto-rendimiento","category-liderazgo","category-recursos-humanos","tag-bienestar","tag-coaching","tag-desempeno-laboral","tag-efectos-negatividad","tag-funcionescognitivas","tag-funcionesejecutivas","tag-negatividad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paula Iba\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Paula Iba\u00f1ez | Desarrollo humano consciente\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez\" \/>\n\t\t<meta property=\"og:description\" content=\"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-11-06T11:20:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-20T12:15:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#article\",\"name\":\"Como te afecta la negatividad en tu desempe\\u00f1o y bienestar | Paula Iba\\u00f1ez\",\"headline\":\"C\\u00f3mo te afecta la negatividad en tu desempe\\u00f1o y bienestar\",\"author\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paulaibanez.cl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Diseno-sin-titulo-17.jpg?fit=2000%2C1600&ssl=1\",\"width\":2000,\"height\":1600,\"caption\":\"Como la negatividad afecta tu desempe\\u00f1o\"},\"datePublished\":\"2020-11-06T08:20:09-03:00\",\"dateModified\":\"2021-03-20T09:15:01-03:00\",\"inLanguage\":\"es-ES\",\"commentCount\":14,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#webpage\"},\"articleSection\":\"coaching, equipos alto rendimiento, liderazgo, Recursos Humanos, bienestar, coaching, desempe\\u00f1o laboral, Efectos negatividad, funcionescognitivas, funcionesejecutivas, negatividad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"name\":\"Recursos Humanos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"position\":2,\"name\":\"Recursos Humanos\",\"item\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#listItem\",\"name\":\"C\\u00f3mo te afecta la negatividad en tu desempe\\u00f1o y bienestar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo te afecta la negatividad en tu desempe\\u00f1o y bienestar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"name\":\"Recursos Humanos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\",\"name\":\"Paula Iba\\u00f1ez\",\"description\":\"Desarrollo humano consciente\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/\",\"name\":\"Paula Iba\\u00f1ez\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#webpage\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/\",\"name\":\"Como te afecta la negatividad en tu desempe\\u00f1o y bienestar | Paula Iba\\u00f1ez\",\"description\":\"Iniciar la ma\\u00f1ana con un estado de \\u00e1nimo negativo puede \\u201coscurecer\\u201d tu d\\u00eda m\\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\\u00f1o laboral.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paulaibanez.cl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Diseno-sin-titulo-17.jpg?fit=2000%2C1600&ssl=1\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#mainImage\",\"width\":2000,\"height\":1600,\"caption\":\"Como la negatividad afecta tu desempe\\u00f1o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\\\/#mainImage\"},\"datePublished\":\"2020-11-06T08:20:09-03:00\",\"dateModified\":\"2021-03-20T09:15:01-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/\",\"name\":\"Paula Iba\\u00f1ez\",\"description\":\"Desarrollo humano consciente\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez","description":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.","canonical_url":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#article","name":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez","headline":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar","author":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"publisher":{"@id":"https:\/\/paulaibanez.cl\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=2000%2C1600&ssl=1","width":2000,"height":1600,"caption":"Como la negatividad afecta tu desempe\u00f1o"},"datePublished":"2020-11-06T08:20:09-03:00","dateModified":"2021-03-20T09:15:01-03:00","inLanguage":"es-ES","commentCount":14,"mainEntityOfPage":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#webpage"},"isPartOf":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#webpage"},"articleSection":"coaching, equipos alto rendimiento, liderazgo, Recursos Humanos, bienestar, coaching, desempe\u00f1o laboral, Efectos negatividad, funcionescognitivas, funcionesejecutivas, negatividad"},{"@type":"BreadcrumbList","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog#listItem","position":1,"name":"Home","item":"https:\/\/paulaibanez.cl\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","name":"Recursos Humanos"}},{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","position":2,"name":"Recursos Humanos","item":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#listItem","name":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#listItem","position":3,"name":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar","previousItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","name":"Recursos Humanos"}}]},{"@type":"Organization","@id":"https:\/\/paulaibanez.cl\/blog\/#organization","name":"Paula Iba\u00f1ez","description":"Desarrollo humano consciente","url":"https:\/\/paulaibanez.cl\/blog\/"},{"@type":"Person","@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author","url":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/","name":"Paula Iba\u00f1ez"},{"@type":"WebPage","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#webpage","url":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/","name":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez","description":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/paulaibanez.cl\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#breadcrumblist"},"author":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"creator":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=2000%2C1600&ssl=1","@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#mainImage","width":2000,"height":1600,"caption":"Como la negatividad afecta tu desempe\u00f1o"},"primaryImageOfPage":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/#mainImage"},"datePublished":"2020-11-06T08:20:09-03:00","dateModified":"2021-03-20T09:15:01-03:00"},{"@type":"WebSite","@id":"https:\/\/paulaibanez.cl\/blog\/#website","url":"https:\/\/paulaibanez.cl\/blog\/","name":"Paula Iba\u00f1ez","description":"Desarrollo humano consciente","inLanguage":"es-ES","publisher":{"@id":"https:\/\/paulaibanez.cl\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Paula Iba\u00f1ez | Desarrollo humano consciente","og:type":"article","og:title":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez","og:description":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.","og:url":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/","article:published_time":"2020-11-06T11:20:09+00:00","article:modified_time":"2021-03-20T12:15:01+00:00","twitter:card":"summary","twitter:title":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | Paula Iba\u00f1ez","twitter:description":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral."},"aioseo_meta_data":{"post_id":"681","title":"Como te afecta la negatividad en tu desempe\u00f1o y bienestar | #site_title","description":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-30 13:04:41","updated":"2025-07-05 19:56:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/paulaibanez.cl\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/\" title=\"Recursos Humanos\">Recursos Humanos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tC\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/paulaibanez.cl\/blog"},{"label":"Recursos Humanos","link":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/"},{"label":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar","link":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=2000%2C1600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6aqPL-aZ","jetpack-related-posts":[{"id":277,"url":"https:\/\/paulaibanez.cl\/blog\/donde-esta-tu-pasion-laboral-lo-que-nadie-te-cuenta\/","url_meta":{"origin":681,"position":0},"title":"\u00bfD\u00f3nde est\u00e1 tu pasi\u00f3n laboral? lo que nadie te cuenta","author":"Paula Iba\u00f1ez","date":"6 marzo, 2016","format":false,"excerpt":"Hay una corriente en perseguir la pasi\u00f3n laboral, pero nadie te cuenta que las pasiones pueden ser ef\u00edmeras y que no siempre se puede por diversas razones. Gettysburg college public\u00f3 que\u00a0las personas usan 90.000 horas en el trabajo\u00a0a lo largo de su vida. A menudo se dice que hagamos un\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Donde est\u00e1 tu pasi\u00f3n laboral","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2016\/03\/1.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2016\/03\/1.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2016\/03\/1.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2016\/03\/1.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2016\/03\/1.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":91,"url":"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/","url_meta":{"origin":681,"position":1},"title":"Manejo de estr\u00e9s en las organizaciones","author":"Paula Iba\u00f1ez","date":"31 mayo, 2015","format":false,"excerpt":"Hay muchos mitos en relaci\u00f3n al estr\u00e9s, sin tener claro qu\u00e9 es, ni c\u00f3mo enfrentarlo. El estr\u00e9s, no es algo malo, es una estrategia adaptativa del cuerpo El estr\u00e9s sucede cuando el cerebro est\u00e1 siendo expuesto a conflictos, exceso de trabajo, exigencias que superan la etapa en que una persona\u2026","rel":"","context":"En \u00abequipos alto rendimiento\u00bb","block_context":{"text":"equipos alto rendimiento","link":"https:\/\/paulaibanez.cl\/blog\/category\/equipos-alto-rendimiento\/"},"img":{"alt_text":"Gesti\u00f3n de estr\u00e9s","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2015\/05\/1.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2015\/05\/1.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2015\/05\/1.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2015\/05\/1.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2015\/05\/1.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":998,"url":"https:\/\/paulaibanez.cl\/blog\/como-puede-afectarte-la-memoria-de-contexto-en-tu-desempeno\/","url_meta":{"origin":681,"position":2},"title":"C\u00f3mo puede afectarte la memoria de contexto en tu desempe\u00f1o","author":"Paula Iba\u00f1ez","date":"5 febrero, 2021","format":false,"excerpt":"Experiencias vividas en tu ambiente laboral se guardan en la memoria de contexto lo que influye en tu comportamiento y toma de decisiones.\u00a0 Un d\u00eda lleg\u00f3 a mi oficina una\u00a0l\u00edder de equipo\u00a0de una multinacional, que llamaremos Daniela, siempre tuvo un desempe\u00f1o destacado, reconocida en su equipo por sus\u00a0decisiones\u00a0oportunas y certeras.\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Como afecta tu desempe\u00f1o","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-05-a-las-23.20.09.png?fit=641%2C499&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-05-a-las-23.20.09.png?fit=641%2C499&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2021\/02\/Captura-de-Pantalla-2021-02-05-a-las-23.20.09.png?fit=641%2C499&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":138,"url":"https:\/\/paulaibanez.cl\/blog\/buscar-un-nuevo-horizonte-laboral\/","url_meta":{"origin":681,"position":3},"title":"Buscar un nuevo horizonte laboral","author":"Paula Iba\u00f1ez","date":"5 julio, 2015","format":false,"excerpt":"Hay momentos en la vida donde nos sentimos inc\u00f3modos con el \u00e1rea laboral en que nos desempe\u00f1amos o con la vida personal que tenemos sin hacer nada al respecto. Los cambios implican salir de la zona de confort aunque no estemos felices. Es lo que conocemos. Lo nuevo pareciera involucrar\u2026","rel":"","context":"En \u00abRecursos Humanos\u00bb","block_context":{"text":"Recursos Humanos","link":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/"},"img":{"alt_text":"Buscar un nuevo horizonte laboral ","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/aromasdeluna\/wp-content\/uploads\/2015\/07\/Blog-Paula-18-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":202,"url":"https:\/\/paulaibanez.cl\/blog\/me-rompiste-el-corazon-como-trabajo-ahora\/","url_meta":{"origin":681,"position":4},"title":"Me rompiste el coraz\u00f3n \u00bfc\u00f3mo trabajo ahora?","author":"Paula Iba\u00f1ez","date":"23 agosto, 2015","format":false,"excerpt":"El concepto de \u201cromper el coraz\u00f3n\u201d pareci\u00f3 algo abstracto y de novelas por mucho tiempo pero la neurociencia nos ha entregado uno m\u00e1s de sus regalos que es conocer los efectos f\u00edsicos del desamor en el cuerpo y, por supuesto, en el cerebro. El cerebro tiene una zona llamada cingular\u2026","rel":"","context":"En \u00abRecursos Humanos\u00bb","block_context":{"text":"Recursos Humanos","link":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/"},"img":{"alt_text":"\u00bfMe rompiste el coraz\u00f3n, c\u00f3mo trabajo ahora?","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/aromasdeluna\/wp-content\/uploads\/2015\/08\/Blog-Paula-33-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":335,"url":"https:\/\/paulaibanez.cl\/blog\/teletrabajo-un-hogar-cerebralmente-amigable\/","url_meta":{"origin":681,"position":5},"title":"Teletrabajo: un hogar cerebralmente amigable","author":"Paula Iba\u00f1ez","date":"9 julio, 2020","format":false,"excerpt":"En teletrabajo un hogar cerebralmente amigable es fundamental para poner en pr\u00e1ctica tus habilidades laborales con una alta motivaci\u00f3n y bajo nivel de estr\u00e9s\u00a0 Es un mi\u00e9rcoles 11:30 am, llevas tres horas de jornada laboral, entrando y saliendo de reuniones virtuales y llamadas por tel\u00e9fono, percibes el cansancio en el\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Casa cerebralmente amigable","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/07\/Captura-de-Pantalla-2020-10-13-a-las-15.32.24.png?fit=699%2C558&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/07\/Captura-de-Pantalla-2020-10-13-a-las-15.32.24.png?fit=699%2C558&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/07\/Captura-de-Pantalla-2020-10-13-a-las-15.32.24.png?fit=699%2C558&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/comments?post=681"}],"version-history":[{"count":7,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/681\/revisions"}],"predecessor-version":[{"id":1110,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/681\/revisions\/1110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/media\/1104"}],"wp:attachment":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/media?parent=681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/categories?post=681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/tags?post=681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}