{"id":891,"date":"2020-12-25T12:56:52","date_gmt":"2020-12-25T15:56:52","guid":{"rendered":"https:\/\/paulaibanez.cl\/blog\/?p=891"},"modified":"2020-12-25T12:56:55","modified_gmt":"2020-12-25T15:56:55","slug":"como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti","status":"publish","type":"post","link":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/","title":{"rendered":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\"><em>Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.\u00a0<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Julio es un gerente de una empresa multinacional, su trabajo le apasiona, cada ma\u00f1ana salta de la cama por el zumbido que le producen sus ideas, casi las puede sentir. Sonido que es interrumpido por las notificaciones de su celular, que desde tempranas horas llegan a su mail, trabajar con otros pa\u00edses con diferente horario es todo un desaf\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julio hace 5 a\u00f1os lleg\u00f3 a esta empresa donde&nbsp;<strong>ha avanzado r\u00e1pidamente<\/strong>&nbsp;en su carrera, est\u00e1 muy feliz, pero la semana pasada me coment\u00f3 que ordenando sus archivos de la computadora lleg\u00f3 a un disco duro que ten\u00eda con fotos antiguas que ni recordaba que estaban ah\u00ed y vio todas las partes de \u00e9l que parec\u00edan im\u00e1genes de alguien m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sol\u00eda correr maratones, ir de vez en cuando de copas con los amigos, escalar cerros, ser un padre presente y un esposo amoroso. Las fotos le hicieron recordar todas las cosas que ya no hac\u00eda y preguntarse&nbsp;<strong>\u00bfD\u00f3nde he estado estos \u00faltimos a\u00f1os?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llego a coaching buscando&nbsp;<strong>equilibrar su vida personal sin detener el crecimiento<\/strong>&nbsp;en su carrera \u201cquiero encontrar las otras partes de mi\u201d, me dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabrina es del \u00e1rea de recursos humanos, con una historia parecida a la de Julio, \u00e9xito en su carrera profesional, pero con\u00a0<strong>poco espacio para el resto de ella<\/strong>, en los \u00faltimos a\u00f1os. No lo hab\u00eda sentido realmente hasta que preocupada not\u00f3 que estaba perdiendo determinaci\u00f3n y energ\u00eda. Su mentalidad de acci\u00f3n r\u00e1pida y su liderazgo, reconocido en el equipo, por su toma de decisi\u00f3n y salida ingeniosa est\u00e1 siendo solo un espejismo de su pasado\u00a0<strong>\u201c\u00bfQu\u00e9 me pas\u00f3?<\/strong>\u00a0\u00bfD\u00f3nde qued\u00f3 el resto de mi?\u201d, me coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabrina en el desarrollo de su carrera hab\u00eda seguido capacit\u00e1ndose en diferentes \u00e1reas como la\u00a0<strong>inteligencia artificial, metodolog\u00edas \u00e1giles<\/strong>, que la complementaban, pero tambi\u00e9n en cierto punto la hac\u00edan ser una extra\u00f1a en esos grupos.\u00a0\u00a0Ya que no era del \u00e1rea digital. As\u00ed empez\u00f3 a tomar caminos seguros, con toma de <strong><a href=\"https:\/\/paulaibanez.cl\/blog\/9-formas-de-mejorar-por-completo-la-toma-de-decision\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/9-formas-de-mejorar-por-completo-la-toma-de-decision\/\" target=\"_blank\" rel=\"noreferrer noopener\">decisiones<\/a><\/strong> apegadas a ambos mundos, detuvo su riesgo e innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de julio y Sabrina, lograron&nbsp;<strong>encontrar el resto del espacio para ellos<\/strong>&nbsp;y sin limitar el crecimiento de su carrera, sino aprovechando la conexi\u00f3n entre sus diferentes, roles e identidades. Ac\u00e1 te cuento como lo lograron.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfD\u00f3nde me paro para consolarme, para evadirme o para salir adelante?<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"549\" data-attachment-id=\"893\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/captura-de-pantalla-2020-12-25-a-las-12-29-47\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?fit=698%2C549&amp;ssl=1\" data-orig-size=\"698,549\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2020-12-25-a-las-12.29.47\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?fit=698%2C549&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?fit=600%2C472&amp;ssl=1\" data-orig-src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?fit=600%2C472&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-893\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27698%27%20height%3D%27549%27%20viewBox%3D%270%200%20698%20549%27%3E%3Crect%20width%3D%27698%27%20height%3D%273549%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?resize=200%2C157&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?resize=300%2C236&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?resize=400%2C315&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?resize=600%2C472&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.47.png?fit=698%2C549&amp;ssl=1 698w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1) Reflexi\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El primer paso es cuando te encuentras en situaciones como Julio y Sabrina, es reconocerla, para luego tomar acciones, cambiar la forma que&nbsp;<strong>piensas&nbsp;<\/strong>de ti y reflexionar sobre tu complejidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces toma papel y l\u00e1piz y <a href=\"https:\/\/paulaibanez.cl\/blog\/el-poder-de-las-preguntas-apropiadas-en-el-ambiente-correcto\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/el-poder-de-las-preguntas-apropiadas-en-el-ambiente-correcto\/\" target=\"_blank\" rel=\"noreferrer noopener\">preg\u00fantate<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo piensas sobre qui\u00e9n eres?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCrees que sabes muchas cosas, pero realmente no eres experto en ninguna?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo afecta tu seguridad y autoestima sentirte como te sientes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfTus m\u00faltiples roles, te hacen sentir m\u00e1s d\u00e9bil o mas fuerte?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfTe preocupa si dedicas mucho tiempo al ti deportista o social, dejes de lado tu avance en tu carrera?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfTus modelos a seguir, act\u00faan as\u00ed?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfConoces alguien que se conecta y desarrolla con m\u00e1s parte de ellos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de ambos gerentes mas arriba mencionados, concluyeron que dedicar m\u00e1s espacio a las otras partes de ellos, les daba miedo y alimentaban su <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/paulaibanez.cl\/blog\/la-mente-hipercritica\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/la-mente-hipercritica\/\" target=\"_blank\">mente hipercr\u00edtica<\/a><\/strong>. Pensaban que detendr\u00eda su ascenso profesional y tuvieron que ir a buscar nuevos modelos a seguir, ya que los que les rodeaban solo estaban \u201calimentando\u201d y dejando crecer una parte de ellos, limitando la posibilidad de interactuar con el resto de sus pasamientos o incluso el desarrollo de otras habilidades en su carrera, que les podr\u00eda adelantarse y ser\u00a0<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/paulaibanez.cl\/blog\/ser-disruptivo-antes-que-te-obliguen-a-serlo\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/ser-disruptivo-antes-que-te-obliguen-a-serlo\/\" target=\"_blank\">disruptivos<\/a><\/strong> en su \u00e1rea.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2) No te dividas<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"547\" data-attachment-id=\"895\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/captura-de-pantalla-2020-12-25-a-las-12-28-20\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?fit=692%2C547&amp;ssl=1\" data-orig-size=\"692,547\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2020-12-25-a-las-12.28.20\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?fit=692%2C547&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?fit=600%2C474&amp;ssl=1\" data-orig-src=\"https:\/\/i1.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?fit=600%2C474&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-895\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27692%27%20height%3D%27547%27%20viewBox%3D%270%200%20692%20547%27%3E%3Crect%20width%3D%27692%27%20height%3D%273547%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?resize=200%2C158&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?resize=300%2C237&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?resize=400%2C316&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?resize=600%2C474&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.28.20.png?fit=692%2C547&amp;ssl=1 692w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A veces las personas se dividen como si fueran peque\u00f1as piezas de un rompecabezas, que compiten por tiempo y atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si desarrollo mi \u201cyo deportista\u201d, de \u201cyo padre\u201d, o \u201cyo con nuevas habilidades laborales\u201d, le quita \u201ca una parte de mi en mi carrera profesional\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>identidades no se apagan ni prenden,<\/strong>&nbsp;sino hay que integrarlas dentro de ti. No te exijas a elegir una identidad o rol sobre los otros, te puede llevar a la confusi\u00f3n y perdida de energ\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo se conectan estos roles?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo puedes sacar provecho?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 son importantes para ti?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo puedes encontrar un tema unificador?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, Julio descubri\u00f3 como pod\u00eda integrar su pasi\u00f3n por el deporte, creando un equipo de running en su empresa. Entrenaban juntos varias veces a la semana, lo que le permiti\u00f3 conocer personas de otras \u00e1reas y trabajar posteriormente de manera m\u00e1s cercana y como equipo en otros proyectos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"545\" data-attachment-id=\"896\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/captura-de-pantalla-2020-12-25-a-las-12-27-39\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?fit=694%2C545&amp;ssl=1\" data-orig-size=\"694,545\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2020-12-25-a-las-12.27.39\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?fit=694%2C545&amp;ssl=1\" src=\"https:\/\/i2.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?fit=600%2C471&amp;ssl=1\" data-orig-src=\"https:\/\/i2.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?fit=600%2C471&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-896\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27694%27%20height%3D%27545%27%20viewBox%3D%270%200%20694%20545%27%3E%3Crect%20width%3D%27694%27%20height%3D%273545%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?resize=200%2C157&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?resize=300%2C236&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?resize=400%2C314&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?resize=600%2C471&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.27.39.png?fit=694%2C545&amp;ssl=1 694w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso lo llev\u00f3 a&nbsp;<strong>un paso m\u00e1s all\u00e1<\/strong>, creando equipos en varios pa\u00edses donde la empresa ten\u00eda filiales y a fin de a\u00f1o realizaron un fundraising para comprar equipos deportivos para escuelas de escasos recursos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces ahora preg\u00fantate&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo puedes <strong>reutilizar tus habilidades <\/strong>aprendidas en tu nuevo rol?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo tu habilidad en\u2026. te permite ser mejor en\u2026? \u00bfPor qu\u00e9?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, personas que han vivido en diferentes pa\u00edses, o se han movido por varias industrias podr\u00edan aprovechar esa adaptabilidad en su nuevo rol, llevarla a su cargo, realizando cruce de lo aprendido y las conexiones que ganaron. Fortaleciendo una cultura organizacional con\u00a0<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/beneficio-de-growth-mindset-en-las-organizaciones\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/beneficio-de-growth-mindset-en-las-organizaciones\/\" target=\"_blank\" rel=\"noreferrer noopener\">mentalidad de crecimiento<\/a><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3) Como te ves, te ven<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para cambiar la relaci\u00f3n que tenemos con los dem\u00e1s el primer paso es cambiar la que se tiene de uno mismo. Enfocarte en los puntos anteriores te ayudar\u00e1 a eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, piensa que podr\u00edas no tener el control sobre todo tu tiempo para poder desarrollar cada uno de tus identidades o roles, pero si puedes colocar l\u00edmite y decidir proactivamente cuanto dedicas a cada una de ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si constantemente est\u00e1s destinando tiempo a tu trabajo y no a tu familia, por que no sabes decir que no, cuando te citan a una reuni\u00f3n tarde, a la larga se resentir\u00e1 tu parte de padre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si para ti es importante desarrollar otras habilidades para tu carrera profesional, sobre todo <strong>pensando en un futuro desafiante<\/strong>, es necesario que le explique a tu equipo o superiores porque los jueves las reuniones no pueden ser m\u00e1s all\u00e1 de las 17 hrs, porque tienes clases. <a href=\"https:\/\/paulaibanez.cl\/blog\/las-conversaciones-y-la-neuroquimica-en-tu-cerebro\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/las-conversaciones-y-la-neuroquimica-en-tu-cerebro\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comun\u00edcalo<\/a> claramente para no crear malos entendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si no ves la importancia de lo que haces, dif\u00edcilmente podr\u00e1s explicarse a los dem\u00e1s y crear el espacio para poder desarrollarla o practicarla.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-fusion-600\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"540\" data-attachment-id=\"894\" data-permalink=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/captura-de-pantalla-2020-12-25-a-las-12-29-02\/\" data-orig-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?fit=694%2C540&amp;ssl=1\" data-orig-size=\"694,540\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Captura-de-Pantalla-2020-12-25-a-las-12.29.02\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?fit=694%2C540&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?fit=600%2C467&amp;ssl=1\" data-orig-src=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?fit=600%2C467&amp;ssl=1\" alt=\"\" class=\"lazyload wp-image-894\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27694%27%20height%3D%27540%27%20viewBox%3D%270%200%20694%20540%27%3E%3Crect%20width%3D%27694%27%20height%3D%273540%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?resize=200%2C156&amp;ssl=1 200w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?resize=300%2C233&amp;ssl=1 300w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?resize=400%2C311&amp;ssl=1 400w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?resize=600%2C467&amp;ssl=1 600w, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.29.02.png?fit=694%2C540&amp;ssl=1 694w\" data-sizes=\"auto\" data-orig-sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Encontrar tu equilibrio es vital en este proceso, donde podr\u00edas decidir potenciar ciertas identidades algunos d\u00edas de la semana, o por temporadas. Asi un rol podr\u00e1 recargar al resto. Por ejemplo, dedicar tiempo a un pasamiento, permitir\u00e1 bajar tu <a href=\"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/manejo-de-estres-en-las-organizaciones\/\" target=\"_blank\" rel=\"noreferrer noopener\">estr\u00e9s<\/a>, luego de eso tomaras mejores decisiones. Entonces estructura tu tiempo y entorno para lograrlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabrina dise\u00f1o un ritual, donde al final de cada mes, no solo med\u00eda las metas del \u00e1rea de recursos humanos de su empresa, sino c\u00f3mo se sent\u00eda al final de cada semana. Pregunt\u00e1ndose de 1 a 10 \u00bfC\u00f3mo est\u00e1 mi energ\u00eda? Y que palabra define mi estado de \u00e1nimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo registraba en un archivo Excel y al final de cada mes, se tomaba unos minutos para evaluar como se sent\u00eda con el tiempo y energ\u00eda que le estaba asignado a sus diferentes habilidades que quer\u00eda desarrollar. Y reflexionaba \u00bfQu\u00e9 cambios debo hacer para el otro mes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de varios meses de trabajo en encontrar el \u201cespacio para si\u201d, Sabrina y Julio lo comentaron con sus equipos, estimul\u00e1ndolo a realizarlo tambi\u00e9n. \u201cRepensemos los modelos a seguir\u201d, as\u00ed iniciaron su kickoff con su\u00a0<strong><a href=\"https:\/\/paulaibanez.cl\/blog\/confianza-el-arma-secreta-de-los-equipos-exitosos\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/confianza-el-arma-secreta-de-los-equipos-exitosos\/\" target=\"_blank\" rel=\"noreferrer noopener\">equipo<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un mundo cambiante y desafiante como el que hoy vivimos estimula a reflexionar sobre nuestras narrativas y lo que ha constituido \u00e9xito hasta hoy, si lo seguir\u00e1 siendo ma\u00f1ana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos abre a la multi-dimensionalidad de nosotros como individuos, ya no es necesario ignorar el resto de qui\u00e9n somos, sino incluirlo para que nos acompa\u00f1e en los siguientes pasos. Ya no existe \u201cuna forma correcta\u201d de hacer las cosas. Los tiempos vividos han mostrado lo contrario.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las organizaciones y<a href=\"https:\/\/paulaibanez.cl\/blog\/como-entender-el-liderazgo-3d-y-su-flexibilidad-de-gestion\/\" data-type=\"URL\" data-id=\"https:\/\/paulaibanez.cl\/blog\/como-entender-el-liderazgo-3d-y-su-flexibilidad-de-gestion\/\" target=\"_blank\" rel=\"noreferrer noopener\"> l\u00edderes<\/a> que se enfrentan proactivamente para los nuevos desaf\u00edos reconocen y valoran el car\u00e1cter multifac\u00e9tico de sus colaboradores, incluso estimul\u00e1ndolos a que desarrollen proyectos personales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te invito a comentar \u00bfC\u00f3mo estas encontrando las otras partes de ti? Y por supuesto a <strong>compartir este blog y suscribirte<\/strong> si aun no lo haces. Todas las semanas comparto sobre neurociencia y coaching para que puedas enfrentar de mejor forma un mundo cambiante y desafiante como el que hoy vivimos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.\u00a0 Julio es un gerente de una empresa multinacional, su trabajo le apasiona, cada ma\u00f1ana salta de la cama por el zumbido que le producen sus ideas, casi las puede sentir. Sonido que es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[259,261,102],"tags":[6,331,334,333],"class_list":["post-891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coaching","category-liderazgo","category-recursos-humanos","tag-coaching","tag-identidad","tag-partesdeti","tag-rol"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paula Iba\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Paula Iba\u00f1ez | Desarrollo humano consciente\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez\" \/>\n\t\t<meta property=\"og:description\" content=\"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-25T15:56:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-12-25T15:56:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#article\",\"name\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\\u00f1ez\",\"headline\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti\",\"author\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paulaibanez.cl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Captura-de-Pantalla-2020-12-25-a-las-12.32.16.png?fit=693%2C552&ssl=1\",\"width\":693,\"height\":552,\"caption\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti\"},\"datePublished\":\"2020-12-25T12:56:52-03:00\",\"dateModified\":\"2020-12-25T12:56:55-03:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#webpage\"},\"articleSection\":\"coaching, liderazgo, Recursos Humanos, coaching, identidad, partesdeti, rol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"name\":\"Recursos Humanos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"position\":2,\"name\":\"Recursos Humanos\",\"item\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#listItem\",\"name\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/category\\\/recursos-humanos\\\/#listItem\",\"name\":\"Recursos Humanos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\",\"name\":\"Paula Iba\\u00f1ez\",\"description\":\"Desarrollo humano consciente\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/\",\"name\":\"Paula Iba\\u00f1ez\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#webpage\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/\",\"name\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\\u00f1ez\",\"description\":\"Administrar diferentes roles se vuelve un desaf\\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \\u00e1reas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/author\\\/lunaroja\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paulaibanez.cl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Captura-de-Pantalla-2020-12-25-a-las-12.32.16.png?fit=693%2C552&ssl=1\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#mainImage\",\"width\":693,\"height\":552,\"caption\":\"C\\u00f3mo encontrar espacio en tu carrera para el resto de ti\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\\\/#mainImage\"},\"datePublished\":\"2020-12-25T12:56:52-03:00\",\"dateModified\":\"2020-12-25T12:56:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/\",\"name\":\"Paula Iba\\u00f1ez\",\"description\":\"Desarrollo humano consciente\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/paulaibanez.cl\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez","description":"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.","canonical_url":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#article","name":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez","headline":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti","author":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"publisher":{"@id":"https:\/\/paulaibanez.cl\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.32.16.png?fit=693%2C552&ssl=1","width":693,"height":552,"caption":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti"},"datePublished":"2020-12-25T12:56:52-03:00","dateModified":"2020-12-25T12:56:55-03:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#webpage"},"isPartOf":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#webpage"},"articleSection":"coaching, liderazgo, Recursos Humanos, coaching, identidad, partesdeti, rol"},{"@type":"BreadcrumbList","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog#listItem","position":1,"name":"Home","item":"https:\/\/paulaibanez.cl\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","name":"Recursos Humanos"}},{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","position":2,"name":"Recursos Humanos","item":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#listItem","name":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti"},"previousItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#listItem","position":3,"name":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti","previousItem":{"@type":"ListItem","@id":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/#listItem","name":"Recursos Humanos"}}]},{"@type":"Organization","@id":"https:\/\/paulaibanez.cl\/blog\/#organization","name":"Paula Iba\u00f1ez","description":"Desarrollo humano consciente","url":"https:\/\/paulaibanez.cl\/blog\/"},{"@type":"Person","@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author","url":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/","name":"Paula Iba\u00f1ez"},{"@type":"WebPage","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#webpage","url":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/","name":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez","description":"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/paulaibanez.cl\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#breadcrumblist"},"author":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"creator":{"@id":"https:\/\/paulaibanez.cl\/blog\/author\/lunaroja\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.32.16.png?fit=693%2C552&ssl=1","@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#mainImage","width":693,"height":552,"caption":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti"},"primaryImageOfPage":{"@id":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/#mainImage"},"datePublished":"2020-12-25T12:56:52-03:00","dateModified":"2020-12-25T12:56:55-03:00"},{"@type":"WebSite","@id":"https:\/\/paulaibanez.cl\/blog\/#website","url":"https:\/\/paulaibanez.cl\/blog\/","name":"Paula Iba\u00f1ez","description":"Desarrollo humano consciente","inLanguage":"es-ES","publisher":{"@id":"https:\/\/paulaibanez.cl\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Paula Iba\u00f1ez | Desarrollo humano consciente","og:type":"article","og:title":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez","og:description":"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.","og:url":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/","article:published_time":"2020-12-25T15:56:52+00:00","article:modified_time":"2020-12-25T15:56:55+00:00","twitter:card":"summary","twitter:title":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | Paula Iba\u00f1ez","twitter:description":"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas."},"aioseo_meta_data":{"post_id":"891","title":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti | #site_title","description":"Administrar diferentes roles se vuelve un desaf\u00edo en el camino de crecimiento en tu carrera, a veces no deja espacio para el resto de ti en otras \u00e1reas.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-30 09:45:35","updated":"2025-07-06 19:56:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/paulaibanez.cl\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/\" title=\"Recursos Humanos\">Recursos Humanos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tC\u00f3mo encontrar espacio en tu carrera para el resto de ti\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/paulaibanez.cl\/blog"},{"label":"Recursos Humanos","link":"https:\/\/paulaibanez.cl\/blog\/category\/recursos-humanos\/"},{"label":"C\u00f3mo encontrar espacio en tu carrera para el resto de ti","link":"https:\/\/paulaibanez.cl\/blog\/como-encontrar-espacio-en-tu-carrera-para-el-resto-de-ti\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/Captura-de-Pantalla-2020-12-25-a-las-12.32.16.png?fit=693%2C552&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6aqPL-en","jetpack-related-posts":[{"id":866,"url":"https:\/\/paulaibanez.cl\/blog\/como-la-inteligencia-emocional-mejora-tu-liderazgo\/","url_meta":{"origin":891,"position":0},"title":"C\u00f3mo la inteligencia emocional mejora tu liderazgo","author":"Paula Iba\u00f1ez","date":"18 diciembre, 2020","format":false,"excerpt":"C\u00f3mo la inteligencia emocional mejora el liderazgo","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"C\u00f3mo la inteligencia emocional mejora el liderazgo","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/5.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/5.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/5.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/5.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/12\/5.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":711,"url":"https:\/\/paulaibanez.cl\/blog\/como-entregar-feedback-efectivo-en-7-pasos\/","url_meta":{"origin":891,"position":1},"title":"Como entregar Feedback efectivo en 7 pasos","author":"Paula Iba\u00f1ez","date":"13 noviembre, 2020","format":false,"excerpt":"El feedback o retroalimentaci\u00f3n en la comunicaci\u00f3n puede sentirse amenazante, en 7 pasos puedes convertirla en una experiencia enriquecedora. Ser capaz de ofrecer feedback\u00a0\u00a0por medio de comentarios constructivos, es fundamental para apoyar a mejorar el desempe\u00f1o de los colaboradores. La retroalimentaci\u00f3n en el momento preciso puede guiar, motivar y reforzar\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Feedback efectivo en 7 pasos","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-13-a-las-09.13.24.png?fit=707%2C561&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-13-a-las-09.13.24.png?fit=707%2C561&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-13-a-las-09.13.24.png?fit=707%2C561&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-13-a-las-09.13.24.png?fit=707%2C561&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":777,"url":"https:\/\/paulaibanez.cl\/blog\/como-pensar-mejor\/","url_meta":{"origin":891,"position":2},"title":"Como pensar mejor","author":"Paula Iba\u00f1ez","date":"27 noviembre, 2020","format":false,"excerpt":"Enfocarse en como pensar mejor permite no desperdiciar el pensamiento sino hacerlo trabajar para ti, siguiendo algunas consideraciones que ac\u00e1 te dejo. Oxford University press en su diccionario define el pensamiento c\u00f3mo \u201cla capacidad que tienen las personas de formar ideas y representaciones de la realidad en su mente, relacionando\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"C\u00f3mo pensar mejor","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/16.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/16.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/16.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/16.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/16.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":759,"url":"https:\/\/paulaibanez.cl\/blog\/que-delegar-y-que-no\/","url_meta":{"origin":891,"position":3},"title":"\u00bfQu\u00e9 Delegar y qu\u00e9 no?","author":"Paula Iba\u00f1ez","date":"20 noviembre, 2020","format":false,"excerpt":"Delegar o no delegar, es la pregunta que se realizan muchos l\u00edderes d\u00eda a d\u00eda, aunque conocen los beneficios de hacerlo, es casi inevitable llenarse de tareas. La delegaci\u00f3n es una habilidad cr\u00edtica, una de las tareas m\u00e1s importante como l\u00edder\u00a0 es ense\u00f1ar a la gente a pensar\u00a0y hacer las\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Que delegar y que no","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-20-a-las-09.36.31.png?fit=694%2C549&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-20-a-las-09.36.31.png?fit=694%2C549&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Captura-de-Pantalla-2020-11-20-a-las-09.36.31.png?fit=694%2C549&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":433,"url":"https:\/\/paulaibanez.cl\/blog\/confianza-el-arma-secreta-de-los-equipos-exitosos\/","url_meta":{"origin":891,"position":4},"title":"Confianza: el arma secreta de los equipos exitosos","author":"Paula Iba\u00f1ez","date":"11 septiembre, 2020","format":false,"excerpt":"Confianza el arma secreta de equipos exitosos","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Confianza el arma secreta de equipos exitosos","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/09\/13.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/09\/13.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/09\/13.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/09\/13.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/09\/13.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":681,"url":"https:\/\/paulaibanez.cl\/blog\/como-te-afecta-la-negatividad-en-tu-desempeno-y-bienestar\/","url_meta":{"origin":891,"position":5},"title":"C\u00f3mo te afecta la negatividad en tu desempe\u00f1o y bienestar","author":"Paula Iba\u00f1ez","date":"6 noviembre, 2020","format":false,"excerpt":"Iniciar la ma\u00f1ana con un estado de \u00e1nimo negativo puede \u201coscurecer\u201d tu d\u00eda m\u00e1s de lo que te imaginas, deteriorando tu bienestar y desempe\u00f1o laboral.\u00a0 No es lo mismo empezar bien el d\u00eda, con tiempo, tomando un buen desayuno, que corriendo de ac\u00e1 para all\u00e1, medio comiendo algo mientras te\u2026","rel":"","context":"En \u00abcoaching\u00bb","block_context":{"text":"coaching","link":"https:\/\/paulaibanez.cl\/blog\/category\/coaching\/"},"img":{"alt_text":"Como la negatividad afecta tu desempe\u00f1o","src":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/paulaibanez.cl\/blog\/wp-content\/uploads\/2020\/11\/Diseno-sin-titulo-17.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/comments?post=891"}],"version-history":[{"count":1,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/891\/revisions"}],"predecessor-version":[{"id":897,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/posts\/891\/revisions\/897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/media\/892"}],"wp:attachment":[{"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/media?parent=891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/categories?post=891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paulaibanez.cl\/blog\/wp-json\/wp\/v2\/tags?post=891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}